{"id":99,"date":"2024-03-23T17:34:09","date_gmt":"2024-03-23T16:34:09","guid":{"rendered":"https:\/\/animmagic.fr\/blog\/?p=99"},"modified":"2022-05-23T17:42:43","modified_gmt":"2022-05-23T15:42:43","slug":"comment-construire-un-plateau-dartistes","status":"publish","type":"post","link":"https:\/\/animmagic.fr\/blog\/2024\/03\/23\/comment-construire-un-plateau-dartistes\/","title":{"rendered":"Comment construire un plateau d\u2019artistes ?"},"content":{"rendered":"<p>Aujourd\u2019hui, on vous explique comment confectionner un plateau d\u2019artistes pour qu\u2019il soit le plus magique et inoubliable possible ! Plusieurs \u00e9tapes sont \u00e0 suivre pour y parvenir :<\/p>\n<p>Tout d\u2019abord, on choisit exclusivement des artistes exp\u00e9riment\u00e9s pour que les transitions soient impeccables. Ensuite, soit on choisit un th\u00e8me soit, on compose un plateau vari\u00e9 avec diff\u00e9rentes disciplines. On d\u00e9termine le temps du spectacle et on r\u00e9unit l\u2019\u00e9quipe artistique. Viens le temps de cr\u00e9ation : On compose la conduite en prenant soin de cr\u00e9er du rythme et en pensant \u00e0 tous les d\u00e9tails mat\u00e9riels pour que le spectacle soit fluide. On pense \u00e0 tout et on anticipe ! Pour finir, on communique avec l\u2019\u00e9quipe pour que chacun puisse effectuer son travail. On r\u00e9unit les musiques et on cr\u00e9e la conduite technique d\u00e9taill\u00e9e pour la transmettre aux techniciens ! Et voil\u00e0, le plateau d\u2019artistes est pr\u00eat \u00e0 \u00e9blouir son public !<\/p>\n<p><a href=\"https:\/\/animmagic.fr\/contact-animmagic-lyon-spectacles-et-animations\/\">nous contacter <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd\u2019hui, on vous explique comment confectionner un plateau d\u2019artistes pour qu\u2019il soit le plus magique et inoubliable possible ! Plusieurs \u00e9tapes sont \u00e0 suivre pour y parvenir :<\/p>\n","protected":false},"author":2,"featured_media":100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[3],"tags":[40,30,12,26,11,5,49,15,44,41,24,34,37,50,53,43,31,36,27,20,25,54,17,32,38,28,16,22,7,56,13,46,19,48,42,10,23,55,51,47,33,29,52,14,18,57,45,9,35,21],"class_list":["post-99","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bien-organiser-son-evenement","tag-acrobates","tag-anciens","tag-animations","tag-anniversaire","tag-arbre","tag-artistes","tag-atelier","tag-ballons","tag-carricaturiste","tag-chanteur","tag-chinoises","tag-closeup","tag-clown","tag-creatif","tag-culturelle","tag-danseurs","tag-ecoles","tag-en","tag-entreprises","tag-formations","tag-grandes","tag-humoriste","tag-illusions","tag-jeune","tag-jongleur","tag-kermes","tag-magicien","tag-magicienne","tag-magie","tag-man","tag-maquillage","tag-maquilleuses","tag-mariage","tag-mascottes","tag-musicien","tag-noel","tag-ombres","tag-one","tag-optiques","tag-pere","tag-public","tag-repas","tag-saison","tag-sculpteur","tag-seminaire","tag-show","tag-silhouettiste","tag-spectacle","tag-table","tag-teambuilding","entry","has-media"],"rttpg_featured_image_url":{"full":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/ventriloquie-unique-qualite-occasion-passes-recents-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"landscape":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/ventriloquie-unique-qualite-occasion-passes-recents-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"portraits":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/ventriloquie-unique-qualite-occasion-passes-recents-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"thumbnail":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/ventriloquie-unique-qualite-occasion-passes-recents-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes-150x150.jpg",150,150,true],"medium":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/ventriloquie-unique-qualite-occasion-passes-recents-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes-300x300.jpg",300,300,true],"large":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/ventriloquie-unique-qualite-occasion-passes-recents-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"1536x1536":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/ventriloquie-unique-qualite-occasion-passes-recents-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"2048x2048":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/ventriloquie-unique-qualite-occasion-passes-recents-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"ocean-thumb-m":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/ventriloquie-unique-qualite-occasion-passes-recents-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"ocean-thumb-ml":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/ventriloquie-unique-qualite-occasion-passes-recents-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",450,450,false],"ocean-thumb-l":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/ventriloquie-unique-qualite-occasion-passes-recents-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false]},"rttpg_author":{"display_name":"Animmagic","author_link":"https:\/\/animmagic.fr\/blog\/author\/animmagic\/"},"rttpg_comment":17,"rttpg_category":"<a href=\"https:\/\/animmagic.fr\/blog\/category\/bien-organiser-son-evenement\/\" rel=\"category tag\">Bien organiser son \u00e9v\u00e8nement<\/a>","rttpg_excerpt":"Aujourd\u2019hui, on vous explique comment confectionner un plateau d\u2019artistes pour qu\u2019il soit le plus magique et inoubliable possible ! Plusieurs \u00e9tapes sont \u00e0 suivre pour y parvenir :","_links":{"self":[{"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/posts\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/comments?post=99"}],"version-history":[{"count":2,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/posts\/99\/revisions"}],"predecessor-version":[{"id":104,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/posts\/99\/revisions\/104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/media\/100"}],"wp:attachment":[{"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/media?parent=99"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/categories?post=99"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/tags?post=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}