{"id":69,"date":"2023-05-23T16:30:03","date_gmt":"2023-05-23T14:30:03","guid":{"rendered":"https:\/\/animmagic.fr\/blog\/?p=69"},"modified":"2022-05-23T17:47:11","modified_gmt":"2022-05-23T15:47:11","slug":"quel-spectacle-pour-quel-public","status":"publish","type":"post","link":"https:\/\/animmagic.fr\/blog\/2023\/05\/23\/quel-spectacle-pour-quel-public\/","title":{"rendered":"Quel spectacle, pour quel public ?"},"content":{"rendered":"<p>Un public, un spectacle. Mais comment bien choisir son spectacle pour qu\u2019il s\u2019adapte parfaitement aux spectateurs ?<\/p>\n<p>Les attentes d\u2019un public compos\u00e9 d\u2019enfants ou d\u2019adultes ne sont pas les m\u00eames. Il existe des spectacles adapt\u00e9s pour toutes les configurations possibles.<\/p>\n<p>Chez Anim\u2019magic on propose des spectacles adapt\u00e9s aux besoins de votre \u00e9v\u00e9nement : pour tous les \u00e2ges, pour un public exclusivement d\u2019adultes, d\u2019enfants ou en famille.<\/p>\n<p><a href=\"https:\/\/animmagic.fr\/contact-animmagic-lyon-spectacles-et-animations\/\">nous contacter<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les attentes d\u2019un public compos\u00e9 d\u2019enfants ou d\u2019adultes ne sont pas les m\u00eames. Il existe des spectacles adapt\u00e9s pour toutes les configurations possibles.<\/p>\n","protected":false},"author":2,"featured_media":70,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[3],"tags":[40,30,12,26,11,5,49,15,44,41,24,34,37,50,53,43,31,36,27,20,25,39,17,32,38,28,16,22,7,13,46,19,48,42,10,23,51,47,33,29,52,14,18,45,9,35,21],"class_list":["post-69","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bien-organiser-son-evenement","tag-acrobates","tag-anciens","tag-animations","tag-anniversaire","tag-arbre","tag-artistes","tag-atelier","tag-ballons","tag-carricaturiste","tag-chanteur","tag-chinoises","tag-closeup","tag-clown","tag-creatif","tag-culturelle","tag-danseurs","tag-ecoles","tag-en","tag-entreprises","tag-formations","tag-grandes","tag-humorise","tag-illusions","tag-jeune","tag-jongleur","tag-kermes","tag-magicien","tag-magicienne","tag-magie","tag-maquillage","tag-maquilleuses","tag-mariage","tag-mascottes","tag-musicien","tag-noel","tag-ombres","tag-optiques","tag-pere","tag-public","tag-repas","tag-saison","tag-sculpteur","tag-seminaire","tag-silhouettiste","tag-spectacle","tag-table","tag-teambuilding","entry","has-media"],"rttpg_featured_image_url":{"full":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/artistes-bulleur-bulles-de-savons-geantes-sculpture-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"landscape":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/artistes-bulleur-bulles-de-savons-geantes-sculpture-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"portraits":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/artistes-bulleur-bulles-de-savons-geantes-sculpture-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"thumbnail":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/artistes-bulleur-bulles-de-savons-geantes-sculpture-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes-150x150.jpg",150,150,true],"medium":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/artistes-bulleur-bulles-de-savons-geantes-sculpture-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes-300x300.jpg",300,300,true],"large":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/artistes-bulleur-bulles-de-savons-geantes-sculpture-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"1536x1536":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/artistes-bulleur-bulles-de-savons-geantes-sculpture-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"2048x2048":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/artistes-bulleur-bulles-de-savons-geantes-sculpture-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"ocean-thumb-m":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/artistes-bulleur-bulles-de-savons-geantes-sculpture-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false],"ocean-thumb-ml":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/artistes-bulleur-bulles-de-savons-geantes-sculpture-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",450,450,false],"ocean-thumb-l":["https:\/\/animmagic.fr\/blog\/wp-content\/uploads\/2022\/05\/artistes-bulleur-bulles-de-savons-geantes-sculpture-animmagic-agence-evenement-spectacle-animation-magie-lyon-region-rhone-alpes.jpg",470,470,false]},"rttpg_author":{"display_name":"Animmagic","author_link":"https:\/\/animmagic.fr\/blog\/author\/animmagic\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/animmagic.fr\/blog\/category\/bien-organiser-son-evenement\/\" rel=\"category tag\">Bien organiser son \u00e9v\u00e8nement<\/a>","rttpg_excerpt":"Les attentes d\u2019un public compos\u00e9 d\u2019enfants ou d\u2019adultes ne sont pas les m\u00eames. Il existe des spectacles adapt\u00e9s pour toutes les configurations possibles.","_links":{"self":[{"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/posts\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":2,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/posts\/69\/revisions"}],"predecessor-version":[{"id":120,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/posts\/69\/revisions\/120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/media\/70"}],"wp:attachment":[{"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/media?parent=69"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/categories?post=69"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/animmagic.fr\/blog\/wp-json\/wp\/v2\/tags?post=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}